{"id":925,"date":"2023-11-28T13:15:13","date_gmt":"2023-11-28T12:15:13","guid":{"rendered":"https:\/\/www.partner-logistic.com\/?p=925"},"modified":"2023-11-28T13:15:13","modified_gmt":"2023-11-28T12:15:13","slug":"allemagne-maut","status":"publish","type":"post","link":"https:\/\/www.partner-logistic.com\/en\/2023\/11\/28\/allemagne-maut\/","title":{"rendered":"Allemagne : MAUT"},"content":{"rendered":"\n<p><strong>Forte augmentation tarifaire \u00e0 partir du 1<sup>er<\/sup>&nbsp;d\u00e9cembre 2023<\/strong><\/p>\n\n\n\n<p><strong>SIMULATION ITLB&nbsp;: + 7,73 %<\/strong><\/p>\n\n\n\n<p>L\u2019Allemagne augmentera prochainement, tr\u00e8s fortement, les tarifs du p\u00e9age kilom\u00e9trique de son r\u00e9seau LKW MAUT.<\/p>\n\n\n\n<p>Toll Collect a officiellement confirm\u00e9 l\u2019entr\u00e9e en vigueur des nouveaux tarifs \u00e0 la date de ce&nbsp;<strong>1<sup>er<\/sup>&nbsp;d\u00e9cembre 2023&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>(voyez\u00a0:\u00a0<\/strong><a rel=\"noreferrer noopener\" href=\"https:\/\/7m8xw.r.a.d.sendibm1.com\/mk\/cl\/f\/sh\/SMK1E8tHeG13ExGKmtoEohoKxZmW\/u5KYpT2G1MNH\" target=\"_blank\"><strong>https:\/\/www.toll-collect.de\/fr\/toll_collect\/bezahlen\/maut_tarife\/p1745_mauttarife_12_2023.html<\/strong><\/a><strong>)<\/strong><\/p>\n\n\n\n<p>Pour rappel, ils reposent sur une diff\u00e9renciation tarifaire bas\u00e9e sur\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/7m8xw.r.a.d.sendibm1.com\/mk\/cl\/f\/sh\/SMK1E8tHeG7uh65Hy3xiuX74vsMm\/O7SvJj3ELBnL\" target=\"_blank\">les \u00e9missions de CO\u2082<\/a>.<\/p>\n\n\n\n<p>A l\u2019initiative de l\u2019UPTR, l\u2019ITLB a proc\u00e9d\u00e9 \u00e0 une simulation de l\u2019impact de cette augmentation sur base des indices du mois de novembre, pour un v\u00e9hicule diesel de la cat\u00e9gorie Euro 6 (classe 1)<\/p>\n\n\n\n<p>La comparaison des indices&nbsp;<em>(nouveaux montants vs. anciens montants)<\/em>&nbsp;donne comme r\u00e9sultat, une augmentation globale du co\u00fbt de revient de&nbsp;7,73 %.<\/p>\n\n\n\n<p>Voyez le tableau de la simulation ci-apr\u00e8s.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ci3.googleusercontent.com\/proxy\/NfNcYFeYbtCh2duSXPU5aURYk-0rT59rGocmNO_jw-cD5n5N8vmfqO7O2zsMjKFOIhWOXFRbsyemvx2r9QbJFnLAgcUtZmmuH5PRk0LYOrb2bhi6sclRCC0-MOXZOshwJrEIeVHxLv0wOzMeuaQ=s0-d-e1-ft#https:\/\/7m8xw.img.a.d.sendibm1.com\/im\/sh\/5rP6jaJWnKKv.png?u=7xwQLFBtniwQnF53TJNJFElKtNIMgPk\" alt=\"\"\/><\/figure>\n\n\n\n<p>Source UPTR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Forte augmentation tarifaire \u00e0 partir du 1er&nbsp;d\u00e9cembre 2023 SIMULATION ITLB&nbsp;: + 7,73 % L\u2019Allemagne augmentera prochainement, tr\u00e8s fortement, les tarifs du p\u00e9age kilom\u00e9trique de son r\u00e9seau LKW MAUT. Toll Collect a officiellement confirm\u00e9 l\u2019entr\u00e9e en vigueur des nouveaux tarifs \u00e0 la date de ce&nbsp;1er&nbsp;d\u00e9cembre 2023&nbsp; (voyez\u00a0:\u00a0https:\/\/www.toll-collect.de\/fr\/toll_collect\/bezahlen\/maut_tarife\/p1745_mauttarife_12_2023.html) Pour rappel, ils reposent sur une diff\u00e9renciation tarifaire bas\u00e9e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/posts\/925"}],"collection":[{"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/comments?post=925"}],"version-history":[{"count":1,"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/posts\/925\/revisions"}],"predecessor-version":[{"id":926,"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/posts\/925\/revisions\/926"}],"wp:attachment":[{"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/media?parent=925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/categories?post=925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.partner-logistic.com\/en\/wp-json\/wp\/v2\/tags?post=925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}